{"id":2371,"date":"2024-09-19T17:06:10","date_gmt":"2024-09-19T17:06:10","guid":{"rendered":"https:\/\/www.innoxnetwork.com\/cross-industry-exchange-in-graz-2024\/"},"modified":"2024-09-19T17:14:25","modified_gmt":"2024-09-19T17:14:25","slug":"cross-industry-exchange-in-graz-2024","status":"publish","type":"post","link":"https:\/\/www.innoxnetwork.com\/en\/cross-industry-exchange-in-graz-2024\/","title":{"rendered":"Cross-industry exchange in Graz"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; left_padding_desktop=&#8221;12%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;12%&#8221; top_padding_phone=&#8221;0%&#8221; bottom_padding_phone=&#8221;5%&#8221; left_padding_phone=&#8221;3%&#8221; right_padding_phone=&#8221;0%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]This cross-industry exchange of experience took place together with Energie Steiermark&#8217;s next incubator at the UNICORN Startup &amp; Innovation Hub at the University of Graz. After a keynote speech by Leadinnovation on the topic of &#8220;Innovation of innovation&#8221;, small groups with hosts from AVL, ANDRITZ, RLB Steiermark and the next incubator discussed the tasks and responsibilities of innovation management, among other things. In the afternoon, Gudrun T\u00f6pfer discussed &#8220;Exnovation &#8211; the neglected flip side of innovation&#8221; &#8211; a topic that also generated a lot of discussion among those present.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][nectar_video_player_self_hosted video_mp4=&#8221;https:\/\/www.innoxnetwork.com\/wp-content\/uploads\/2024\/09\/2024_CROSS-INDUSTRY_Austausch_Graz_low.mp4&#8243; video_image=&#8221;2296&#8243; player_functionality=&#8221;default&#8221; autoplay=&#8221;yes&#8221; video_loading=&#8221;default&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; left_padding_desktop=&#8221;12%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;12%&#8221; top_padding_phone=&#8221;0%&#8221; bottom_padding_phone=&#8221;5%&#8221; left_padding_phone=&#8221;3%&#8221; right_padding_phone=&#8221;0%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2368,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2371","post","type-post","status-publish","format-standard","has-post-thumbnail","category-2024-en"],"_links":{"self":[{"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/posts\/2371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/comments?post=2371"}],"version-history":[{"count":8,"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/posts\/2371\/revisions"}],"predecessor-version":[{"id":2383,"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/posts\/2371\/revisions\/2383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/media\/2368"}],"wp:attachment":[{"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/media?parent=2371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/categories?post=2371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.innoxnetwork.com\/en\/wp-json\/wp\/v2\/tags?post=2371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}